{"id":7254,"date":"2016-01-14T16:09:15","date_gmt":"2016-01-14T16:09:15","guid":{"rendered":"https:\/\/kasperskydaily.com\/italy\/?p=7254"},"modified":"2020-02-26T17:30:13","modified_gmt":"2020-02-26T15:30:13","slug":"kid-safety-iot","status":"publish","type":"post","link":"https:\/\/www.kaspersky.it\/blog\/kid-safety-iot\/7254\/","title":{"rendered":"Proteggete i vostri bambini e ragazzi dagli hacker"},"content":{"rendered":"<p>Essere genitore \u00e8 difficile. I genitori devono preoccuparsi di troppe cose quando si tratta dei loro figli, passando dall\u2019infanzia e la scuola, alla sana alimentazione e le ore davanti alla TV. Quindi, perch\u00e9 aggiungere preoccupazioni inutili alle loro indaffarate vite quotidiane?<\/p>\n<p>Il punto \u00e8 proprio questo: i genitori hanno molte preoccupazioni e cercano la comodit\u00e0. Tutto ci\u00f2 che pu\u00f2 far risparmiare loro tempo o fatica viene valutato positivamente. Alcuni esempi potrebbero essere servizi come Netflix, Amazon o il cibo a domicilio.<\/p>\n<p>Tuttavia, le app sono solo la punta dell\u2019iceberg. Viviamo nel mondo in espansione di <em>Internet delle Cose<\/em>, quindi esistono anche dispositivi intelligenti in grado di dare una mano ai genitori, come i baby monitor, i tablet per bambini e le Barbie che aiutano a vigilare o intrattenere i marmocchi.<\/p>\n<p>Purtroppo per\u00f2, presi dal tran tran quotidiano, i genitori pensano di pi\u00f9 a come semplificare le cose,\u00a0 e se queste cose piaceranno ai figli, piuttosto che alla sicurezza. Ecco dove la comodit\u00e0 ci si pu\u00f2 ritorcere contro.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Well this is a bit freaky: \"Couple whose baby monitor was hacked has message for other families\": <a href=\"http:\/\/t.co\/vziFqVxPTI\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/vziFqVxPTI<\/a><\/p>\n<p>\u2014 Troy Hunt (@troyhunt) <a href=\"https:\/\/twitter.com\/troyhunt\/status\/591050943900164096?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">April 23, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Odio leggere in rete storie di baby monitor hackerati. Sembra che ogni 3 o 6 mesi qualche pazzo <a href=\"http:\/\/sfglobe.com\/2016\/01\/06\/stranger-hacks-familys-baby-monitor-and-talks-to-child-at-night\/\" target=\"_blank\" rel=\"noopener nofollow\">decida di infastidire qualche famiglia<\/a>. Qui il profitto o il piacere che si pu\u00f2 ricavare dal violare un dispositivo non ha scusa: con i bambini non si scherza, \u00e8 sbagliato.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Stranger hacks family's baby monitor and talks to child at night <a href=\"https:\/\/twitter.com\/hashtag\/IoT?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#IoT<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/kids?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#kids<\/a><a href=\"https:\/\/t.co\/yTuxZMfcGP\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/t.co\/yTuxZMfcGP<\/a> <a href=\"https:\/\/t.co\/OfzOkklxDI\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/OfzOkklxDI<\/a><\/p>\n<p>\u2014 Alex Drozhzhin (@GrzegorzBr) <a href=\"https:\/\/twitter.com\/GrzegorzBr\/status\/687640493363212290?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">January 14, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>La faccenda \u00e8 piuttosto delicata, ma possiamo imparare qualcosa da tutto questo: siamo tutti <strong>responsabili<\/strong> di qualsiasi dispositivo connesso a Internet delle Cose di nostra appartenenza, e dobbiamo stare ancora pi\u00f9 attenti quando uno QUALUNQUE di questi oggetti legati\u00a0 o vicino ai nostri bambini si collega al Web.<\/p>\n<p>https:\/\/www.instagram.com\/p\/-yoE2gv0DD\/<\/p>\n<p>Quando qualcuno viola un dispositivo pensato per vostro figlio e connesso all\u2019Internet delle Cose, possono verificarsi situazioni allarmanti, persino peggiori di quelle paventate dall\u2019articolo sopra menzionato. Esse includono il furto d\u2019identit\u00e0, lo stalking e l\u2019estorsione.<\/p>\n<p>Detto ci\u00f2, qualora vi decideste, vi esortiamo a pensare alla sicurezza informatica, e non ve lo diciamo solo per il vostro bene, ma anche per quello dei vostri piccoli.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">How <a href=\"https:\/\/twitter.com\/hashtag\/cybersavvy?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#cybersavvy<\/a> are you? Find out in our quiz: <a href=\"https:\/\/t.co\/DgDPNu9P47\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/t.co\/DgDPNu9P47<\/a> <a href=\"http:\/\/t.co\/4DhyKTxSKQ\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/4DhyKTxSKQ<\/a><\/p>\n<p>\u2014 Kaspersky (@kaspersky) <a href=\"https:\/\/twitter.com\/kaspersky\/status\/648882239011426304?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">September 29, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3>Avete bisogno di connettervi a Internet?<\/h3>\n<p>Sono cresciuto senza Internet; usavo quella cosa chiamata immaginazione, sono sicuro che ne avete sentito parlare. La domanda che spesso mi pongo \u00e8: ai miei figli serve questo oggetto? Hanno bisogno di stare online?<\/p>\n<p>Il pi\u00f9 delle volte, davvero non riesco a giustificare la ragione per cui un giocattolo debba essere connesso al mio telefono, tablet o al Web.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">3.3M Hello Kitty accounts compromised\u2026 <a href=\"https:\/\/t.co\/Ub9Cy30YT3\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/t.co\/Ub9Cy30YT3<\/a> <a href=\"https:\/\/t.co\/iE0BowBdwr\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/iE0BowBdwr<\/a><\/p>\n<p>\u2014 Kaspersky (@kaspersky) <a href=\"https:\/\/twitter.com\/kaspersky\/status\/678969968684331009?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">December 21, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Se pensate il contrario o se il giocattolo \u00e8 essenziale, vi prego di leggere attentamente i diritti d\u2019accesso e quali informazioni \u00e8 necessario che il produttore raccolga su di voi o i vostri figli. In tutta onest\u00e0, che bisogno c\u2019\u00e8 di condividere le coordinate GPS o far sapere in che scuola va vostro figlio?<\/p>\n<h3>La vostra rete domestica \u00e8 sicura?<\/h3>\n<p>I bambini di oggi non cresceranno mai come sono cresciuto io. Internet \u00e8 dappertutto ed \u00e8 fondamentale per la vita quotidiana. Quindi che vi piaccia o no, la connettivit\u00e0 all\u2019interno delle nostre case continuer\u00e0 a crescere.<\/p>\n<p>Vedete pubblicit\u00e0 che promuovono la sicurezza domestica e videocamere fornite di Wi-Fi, e poich\u00e9 l\u2019Internet delle Cose \u00e8 in espansione, le aziende vogliono vendere questi dispositivi. Logicamente, tutti vogliamo essere sicuri e sentirci protetti all\u2019interno delle nostre case. Tuttavia, \u00e8 proprio questa necessit\u00e0 a tradirci perch\u00e9 oltre a noi stessi, \u00e8 necessario proteggere anche tutti i dati contenuti in quei dispositivi, dati che, per i cybercriminali, sono ben pi\u00f9 preziosi di una TV a 60 pollici o di un cimelio sportivo.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">More connected, less secure: how we probed <a href=\"https:\/\/twitter.com\/hashtag\/IoT?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#IoT<\/a> for vulnerabilities <a href=\"https:\/\/t.co\/f4Y6iXLG8U\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/t.co\/f4Y6iXLG8U<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/internetofthings?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#internetofthings<\/a> <a href=\"https:\/\/t.co\/ZwFbvGGW6G\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/ZwFbvGGW6G<\/a><\/p>\n<p>\u2014 Kaspersky (@kaspersky) <a href=\"https:\/\/twitter.com\/kaspersky\/status\/662276796310769664?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">November 5, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>\u00c8 possibile che molti di voi non abbiano tenuto in considerazione questi aspetti, ma come minimo, dovreste proteggere con password il vostro router wireless e installare un antivirus nei vostri dispositivi. <a href=\"https:\/\/www.kaspersky.com\/it\/free-trials\/multi-device-security?redef=1&amp;reseller=it_socmed_pro_ona_smm__onl_b2c__lnk____kismd___\" target=\"_blank\" rel=\"noopener nofollow\">Kaspersky Internet Security<\/a> pu\u00f2 proteggere varie dispositivi nello stesso tempo.<\/p>\n<h3>Pensate ai vostri figli<\/h3>\n<p>Tra i vostri compiti come genitori vi \u00e8 quello di accompagnare i vostri figli verso le loro mete personali. Dovremmo quindi trattare la loro privacy come faremmo con la loro incolumit\u00e0 e pensare anche nel futuro.<\/p>\n<p>A differenza di un adulto a cui venga rubata l\u2019identit\u00e0, potrebbero passare anni (o decine di anni) prima che si venga a sapere, poich\u00e9 durante l\u2019infanzia non controlleranno i suoi movimenti bancari. Comprare per loro \u00e8 compito vostro.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" type=\"text\/html\" width=\"640\" height=\"390\" src=\"https:\/\/www.youtube.com\/embed\/BQ4yd2W50No?version=3&amp;rel=1&amp;fs=1&amp;showsearch=0&amp;showinfo=1&amp;iv_load_policy=1&amp;start=14&amp;wmode=transparent\" frameborder=\"0\" allowfullscreen=\"true\"><\/iframe><\/span><\/p>\n<p>Tenendo questo a mente, dovete stare davvero attenti ai dati che condividete con le aziende. Se un gioco o un account necessitasse di informazioni vitali, prendete in considerazione questi tre consigli:<\/p>\n<ol>\n<li>Condividete il meno possibile. Non c\u2019\u00e8 scritto da nessuna parte che dovete dare informazioni essenziali ai produttori di giocattoli\u2026 e neanche ai dottori.<\/li>\n<li>Inventate dati falsi. Se non volete che il profilo di vostro figlio venga tracciato dalle aziende e dalle principali marche sul mercato, inventate date di nascita, sesso, preferenze o qualunque altra sciocchezza vi venga chiesta. Gli esperti di marketing vengono pagati per questo, non c\u2019\u00e8 bisogno che gli sfacilitiate le cose.<\/li>\n<li>Usate le vostre informazioni. Non esiste una regola ferrea per cui l\u2019account di un utente debba essere legato a vostro figlio. Sono abbastanza sicuro che ci siano almeno tre account dei miei figli con i miei dati.<\/li>\n<\/ol>\n<p>Sono un genitore e so che avete tanta carne al fuoco. Un bel respiro profondo: potete farcela. Se avete bisogno di un incoraggiamento positivo, date un\u2019occhiata a questo video.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" type=\"text\/html\" width=\"640\" height=\"390\" src=\"https:\/\/www.youtube.com\/embed\/qztuEucrNBc?version=3&amp;rel=1&amp;fs=1&amp;showsearch=0&amp;showinfo=1&amp;iv_load_policy=1&amp;wmode=transparent\" frameborder=\"0\" allowfullscreen=\"true\"><\/iframe><\/span><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Internet delle Cose \u00e8 sempre meno protetto. Fate attezione ai baby monitor e a tutti i dispositivi collegati a Internet vicini ai vostri bambini e ragazzi! <\/p>\n","protected":false},"author":636,"featured_media":7255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16,2641,12],"tags":[1785,620,45,1786],"class_list":{"0":"post-7254","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tips","8":"category-threats","9":"category-news","10":"tag-baby-monitor-hackerati","11":"tag-internet-delle-cose","12":"tag-sicurezza","13":"tag-sicurezza-dellinternet-delle-cose"},"hreflang":[{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/kid-safety-iot\/7254\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/kid-safety-iot\/5279\/"},{"hreflang":"ar","url":"https:\/\/me.kaspersky.com\/blog\/kid-safety-iot\/3671\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/kid-safety-iot\/6542\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/kid-safety-iot\/6624\/"},{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/kid-safety-iot\/6536\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/kid-safety-iot\/7510\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/kid-safety-iot\/10587\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/kid-safety-iot\/11066\/"},{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/kid-safety-iot\/6280\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/kid-safety-iot\/6757\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/kid-safety-iot\/10085\/"},{"hreflang":"ru-kz","url":"https:\/\/blog.kaspersky.kz\/kid-safety-iot\/10587\/"},{"hreflang":"en-au","url":"https:\/\/www.kaspersky.com.au\/blog\/kid-safety-iot\/11066\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/kid-safety-iot\/11066\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.it\/blog\/tag\/baby-monitor-hackerati\/","name":"Baby monitor hackerati"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/7254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/users\/636"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/comments?post=7254"}],"version-history":[{"count":3,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/7254\/revisions"}],"predecessor-version":[{"id":20692,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/7254\/revisions\/20692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media\/7255"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media?parent=7254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/categories?post=7254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/tags?post=7254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}