{"id":5844,"date":"2015-04-03T10:24:36","date_gmt":"2015-04-03T10:24:36","guid":{"rendered":"http:\/\/kasperskydaily.com\/italy\/?p=5844"},"modified":"2019-11-22T11:32:34","modified_gmt":"2019-11-22T09:32:34","slug":"progetti-interessanti-big-data","status":"publish","type":"post","link":"https:\/\/www.kaspersky.it\/blog\/progetti-interessanti-big-data\/5844\/","title":{"rendered":"11 progetti  interessanti che coinvolgono i Big Data"},"content":{"rendered":"<p>In tanti parlano dei cosiddetti \u201c<a href=\"http:\/\/it.wikipedia.org\/wiki\/Big_data\" target=\"_blank\" rel=\"noopener nofollow\">Big Data<\/a>\u201c, dei lati positivi e negativi o del loro potenziale; per questo, non possiamo fare a meno di dire la nostra su alcuni progetti in tutto il mondo che prevedono l\u2019uso dei Big Data. Ci siamo imbattuti in idee tra il serio e il faceto, e abbiamo trovato anche progetti sorprendenti. Pronti? Via!<\/p>\n<p>Ebbene, i Big Data ci aiuteranno a\u2026<\/p>\n<p><strong>1: Trovare su Internet esattamente quello che cerchiamo<\/strong><\/p>\n<p>Forse non ci avete mai pensato, ma i grandi motori di ricerca come Google, Yahoo, Yandex o Bing lavorano con i Big Data quando ci mostrano i risultati.<\/p>\n<p>I motori di ricerca gestiscono migliaia di miliardi di oggetti in Rete e analizzano il comportamento online di miliardi di utenti per comprendere cosa stiamo cercando esattamente su Internet. \u00c8 normale, quindi, che questi giganti della tecnologia siano stati i pionieri nel settore dell\u2019analisi dei dati (di tutti i campi) e che mettano in commercio prodotti che abbiano qualche vincolo con i Big Data.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" type=\"text\/html\" width=\"640\" height=\"390\" src=\"https:\/\/www.youtube.com\/embed\/YuOBzWF0Aws?version=3&amp;rel=1&amp;fs=1&amp;showsearch=0&amp;showinfo=1&amp;iv_load_policy=1&amp;wmode=transparent\" frameborder=\"0\" allowfullscreen=\"true\"><\/iframe><\/span><\/p>\n<p><strong>2: Guidare in citt\u00e0 evitando il traffico<\/strong><\/p>\n<p>Ad esempio, Yandex Company ha raffinato le sue abilit\u00e0 nel campo dell\u2019analisi dei dati, osservandoli da un differente punto di vista. Ed \u00e8 cos\u00ec che \u00e8 nata la soluzione <a href=\"https:\/\/company.yandex.com\/technologies\/traffic_jams_technology.xml\" target=\"_blank\" rel=\"noopener nofollow\">Yandex Traffic<\/a>, che analizza le informazioni provenienti da varie fonti e mostra in tempo reale il traffico in una determinata citt\u00e0.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">And it's a number 9 (out of 9) on the Yandex traffic ratings! <a href=\"https:\/\/twitter.com\/hashtag\/Moscow?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#Moscow<\/a> <a href=\"http:\/\/t.co\/j6zgyJbm0g\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/j6zgyJbm0g<\/a><\/p>\n<p>\u2014 Jack Farchy (@jfarchy) <a href=\"https:\/\/twitter.com\/jfarchy\/status\/476734493685219330?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">June 11, 2014<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Il servizio \u00e8 disponibile per grandi citt\u00e0, dove il traffico pu\u00f2 essere davvere una spina nel fianco degli automobilisti. Siete mai stati a Mosca? Vi diamo un consiglio spassionato: se doveste andarci, date un\u2019occhiata a questo servizio, potrebbe esservi molto utile e gi\u00e0 lo usano milioni di moscoviti.<\/p>\n<p><strong>3: Salvare animali in via di estinzione e catturare i bracconieri<\/strong><\/p>\n<p><a href=\"http:\/\/www.huffingtonpost.com\/2015\/01\/12\/india-wild-tigers-big-data_n_6458386.html\" target=\"_blank\" rel=\"noopener nofollow\">I bracconieri cacciano le tigri indiane in via di estinzione<\/a> per ricavare dalle loro ossa dei medicinali molto popolari nella cultura e nella superstizione cinesi. Conoscono a menadito tutte le zone dove vivono le tigri e sarebbe davvero difficile catturare questi delinquenti senza l\u2019aiuto\u2026 dei Big Data.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Study uses big data to target and thwart Indian tiger poachers <a href=\"http:\/\/t.co\/wXSMLz1ivK\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/wXSMLz1ivK<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/wildlife?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#wildlife<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/animal?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#animal<\/a><\/p>\n<p>\u2014 \u267b\ufe0f emrals.com \u267b\ufe0f (@EmralsGlobal) <a href=\"https:\/\/twitter.com\/EmralsGlobal\/status\/557970966287228931?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">January 21, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>4: Rendere pi\u00f9 \u201cgreen\u201d le nostre citt\u00e0<\/strong><\/p>\n<p><a href=\"http:\/\/www.cio.com\/article\/2385245\/data-management\/new-york-turns-to-big-data-to-solve-big-tree-problem.html\" target=\"_blank\" rel=\"noopener nofollow\">New York sta diventando una citt\u00e0 sempre pi\u00f9 pericolosa<\/a> per via di vecchi alberi che cadono all\u2019improvviso colpendo ignari cittadini e abitazioni. Le autorit\u00e0 competenti non hanno ancora trovato la soluzione a questo problema. Ora, per\u00f2, i Big Data ci potrebbero aiutare a mantenere in buone salute i polmoni verdi nelle nostre citt\u00e0.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Pretty cool: \"New York Turns to Big Data to Solve Big Tree Problem <a href=\"http:\/\/t.co\/ah0ceZ1hoJ\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/ah0ceZ1hoJ<\/a> via <a href=\"https:\/\/twitter.com\/CIOonline?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">@CIOonline<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/CIO?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#CIO<\/a><\/p>\n<p>\u2014 Debra Bulkeley (@dbulk) <a href=\"https:\/\/twitter.com\/dbulk\/status\/342384721021513728?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">June 5, 2013<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>5: Comprendere perch\u00e9 la cucina indiana \u00e8 veramente unica <\/strong><\/p>\n<p><a href=\"http:\/\/www.technologyreview.com\/view\/535451\/data-mining-indian-recipes-reveals-new-food-pairing-phenomenon\/\" target=\"_blank\" rel=\"noopener nofollow\">Alcuni scienziati hanno analizzato un numero infinito di ricette<\/a> e hanno scoperto che la teoria della combinazioni di cibi funziona per tutte le cucine del mondo, tranne per quella indiana.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Negative food pairing in Indian cuisine \u2013 because science. <a href=\"http:\/\/t.co\/mo158dyNzC\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/mo158dyNzC<\/a> pdf <a href=\"http:\/\/t.co\/zwwNiikYpa\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/zwwNiikYpa<\/a> <a href=\"http:\/\/t.co\/0a62KzF3pv\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/0a62KzF3pv<\/a><\/p>\n<p>\u2014 rohit (@rohit_x_) <a href=\"https:\/\/twitter.com\/rohit_x_\/status\/570813466597961728?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">February 26, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>6: Combattere l\u2019epidemia di malaria in Africa<\/strong><\/p>\n<p><a href=\"http:\/\/www.wired.com\/2014\/12\/malaria-no-more-google\/\" target=\"_blank\" rel=\"noopener nofollow\">Un grande progetto sostenuto da Google<\/a> prevede l\u2019uso dei Big Data per risolvere importanti problemi riguardanti la salute mondiale. Molti africani hanno un telefono cellulare, anche se vivono in localit\u00e0 remote. I pazienti affetti da malaria potranno inviare messaggi di testo per informare i medici sui medicinali che stanno prendendo; in questo modo gli scienziati conosceranno il grado di diffusione della malattia e le percentuali di cura.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Fighting Malaria With Mobile Phones <br>Google lending the services of its data scientists for 'Malaria No More'.<a href=\"http:\/\/t.co\/Jsj8ZczEHj\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/Jsj8ZczEHj<\/a><\/p>\n<p>\u2014 AwesomeNaz (@awesome_naz) <a href=\"https:\/\/twitter.com\/awesome_naz\/status\/546354002351239168?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">December 20, 2014<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>7:Far crescere i migliori alberi di Natale<\/strong><\/p>\n<p><a href=\"http:\/\/today.uconn.edu\/blog\/2014\/12\/big-data-and-the-science-of-the-christmas-tree\/\" target=\"_blank\" rel=\"noopener nofollow\">Gli scienziati potranno avere un quadro generale dei dati che riguardano la genetica, gli aspetti fisici e l\u2019ambiente<\/a>, presenti nei 15 principali database di piante per creare migliori semi, migliori specie vegetali e, in teoria, anche per ottenere l\u2019albero di Natale perfetto.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">The secret to the perfect Christmas tree just might be big data. <a href=\"http:\/\/t.co\/TyQvpC1hXP\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/TyQvpC1hXP<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/BitFeed?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#BitFeed<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ITCenter?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#ITCenter<\/a> <a href=\"http:\/\/t.co\/YWAm81dkXH\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/YWAm81dkXH<\/a><\/p>\n<p>\u2014 Intel Business (@IntelBusiness) <a href=\"https:\/\/twitter.com\/IntelBusiness\/status\/546772850972327936?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">December 21, 2014<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>8: Comprendere che le lingue parlate nel mondo sono piene di messaggi positivi<\/strong><\/p>\n<p>\u00c8 emerso che <a href=\"http:\/\/www.theatlantic.com\/health\/archive\/2015\/02\/language-is-biased-toward-happiness\/385348\/\" target=\"_blank\" rel=\"noopener nofollow\">le lingue nel mondo contengono un maggior numero di parole dal significato positivo che negativo<\/a>. Siamo predisposti alla felicit\u00e0.<\/p>\n<p>https:\/\/twitter.com\/storagesport\/status\/565297921697271812<\/p>\n<p><strong>9: Rendere gli eventi sportivi ancora pi\u00f9 avvincenti<\/strong><\/p>\n<p><a href=\"http:\/\/www.forbes.com\/sites\/bernardmarr\/2015\/03\/25\/big-data-the-winning-formula-in-sports\/\" target=\"_blank\" rel=\"noopener nofollow\">Gli allenatori delle squadre pi\u00f9 importanti utilizzano i Big Data<\/a> per gli allenamenti, i programmi alimentari e persino per gestire le interazioni con i fan con lo scopo di migliorare le prestazioni sul campo.<\/p>\n<p>https:\/\/twitter.com\/Antivia\/status\/582302015302184960<\/p>\n<p><strong>10: Migliorare le condizioni di lavoro<\/strong><\/p>\n<p>I capi sanno tutto. O <a href=\"http:\/\/www.newsweek.com\/plan-quit-big-data-might-tell-your-boss-you-do-298026\" target=\"_blank\" rel=\"noopener nofollow\">almeno verranno a sapere quando i propri impiegati vogliono lasciare il lavoro<\/a>, grazie ai Big Data. E avranno anche qualche dritta su come migliorare le condizioni lavorative e mantenere i dipendenti soddisfatti.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">How your boss already knows if you want to quit your job?Excellent summary by @Nikelle_CS <a href=\"https:\/\/twitter.com\/hashtag\/turnover?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#turnover<\/a> <a href=\"http:\/\/t.co\/IbksEkw0io\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/IbksEkw0io<\/a><\/p>\n<p>\u2014 the WorkLife HUB (@WorkLifeHUB) <a href=\"https:\/\/twitter.com\/WorkLifeHUB\/status\/581528715034787840?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">March 27, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>11: Migliorare le relazioni interpersonali<\/strong><\/p>\n<p>Ultimo ma non meno importante \u00e8 un caso reso noto recentemente dai media. L\u2019analisi dei dati pu\u00f2 servire per risolvere \u00a0problemi che coinvolgono l\u2019opinione pubblica ma anche questioni molto personali. Leggete la storia di un analista di dati sugli <a href=\"http:\/\/fivethirtyeight.com\/features\/in-the-end-people-may-really-just-want-to-date-themselves\/\" target=\"_blank\" rel=\"noopener nofollow\">incontri online<\/a> che ha effettuato uno <a href=\"http:\/\/www.businessinsider.com\/two-big-lessons-about-love-2015-4\" target=\"_blank\" rel=\"noopener nofollow\">studio statistico sulla propria relazione amorosa<\/a>.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Analyzing over 5,500 emails with her boyfriend taught this statistician two big lessons abo\u2026 <a href=\"http:\/\/t.co\/YVxc5HNXoR\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/YVxc5HNXoR<\/a> <a href=\"http:\/\/t.co\/ctKVrTrY0E\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/ctKVrTrY0E<\/a><\/p>\n<p>\u2014 Business Insider (@BusinessInsider) <a href=\"https:\/\/twitter.com\/BusinessInsider\/status\/583727584904613890?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">April 2, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Sapevate che <a href=\"https:\/\/datafloq.com\/read\/dark-data-big-datas-best-friend\/950\" target=\"_blank\" rel=\"noopener nofollow\">il 90% dei Big Data immagazzinati costituisce un peso morto<\/a>? I cosiddetti Dark Data sono porzioni di dati che sembrano utili e che occupano uno spazio discreto della memoria ma che in realt\u00e0 non ci servono quotidianamente. Si tratta di una buona notizia in quanto ci\u00f2 dimostra il grande potenziale del data mining e dell\u2019analisi. I Dark Data stanno aspettando che una mente curiosa faccia buon uso di questa risorsa. Se state decidendo dove mandare i vostri figli all\u2019universit\u00e0, pensate a quanto vi stiamo dicendo.<\/p>\n<blockquote class=\"twitter-pullquote\"><p>Idee serie, semiserie e sorprendenti per utilizzare i #BigData.<\/p><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fkas.pr%2FxBR1&amp;text=Idee+serie%2C+semiserie+e+sorprendenti+per+utilizzare+i+%23BigData.\" class=\"btn btn-twhite\" data-lang=\"en\" data-count=\"0\" target=\"_blank\" rel=\"noopener nofollow\">Tweet<\/a><\/blockquote>\n<p>Per oggi \u00e8 tutto. La prossima settimana pubblicheremo un altro post su nuovi progetti con i Big Data, in particolare parleremo di come possono salvare delle vite e a catturare i criminali. A presto!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci sono molti progetti interessanti oltre che divertenti che prevedono l\u2019uso dei Big Data. Abbiamo raccolto gli 11 pi\u00f9 importanti. Leggere per credere!<\/p>\n","protected":false},"author":522,"featured_media":5845,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[1433,1359,1434,841,114,1435,1335,33,685,1436],"class_list":{"0":"post-5844","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"tag-analisi-dei-dati","9":"tag-big-data","10":"tag-data-mining","11":"tag-dati","12":"tag-dispositivi-mobili","13":"tag-divertimento","14":"tag-futuro","15":"tag-google","16":"tag-salute","17":"tag-yandex"},"hreflang":[{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/progetti-interessanti-big-data\/5844\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.it\/blog\/tag\/analisi-dei-dati\/","name":"analisi dei dati"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/5844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/users\/522"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/comments?post=5844"}],"version-history":[{"count":2,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/5844\/revisions"}],"predecessor-version":[{"id":19073,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/5844\/revisions\/19073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media\/5845"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media?parent=5844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/categories?post=5844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/tags?post=5844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}