{"id":4287,"date":"2014-07-07T13:30:44","date_gmt":"2014-07-07T13:30:44","guid":{"rendered":"http:\/\/kasperskydaily.com\/italy\/?p=4287"},"modified":"2021-04-28T16:25:51","modified_gmt":"2021-04-28T14:25:51","slug":"i-principali-casi-di-cybercrimine-del-mese-giugno-2014","status":"publish","type":"post","link":"https:\/\/www.kaspersky.it\/blog\/i-principali-casi-di-cybercrimine-del-mese-giugno-2014\/4287\/","title":{"rendered":"I principali casi di cybercrimine del mese: giugno 2014"},"content":{"rendered":"<p>Con giugno \u00e8 arrivata finalmente l\u2019estate. Ma i cybercriminali e le forze dell\u2019ordine non sono andati in vacanza. Diamo un\u2019occhiata ai principali arresti del mese scorso.<\/p>\n<h3><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/89\/2014\/07\/05232810\/Guccifer.jpg\" alt=\"\" width=\"200\" height=\"280\">Guccifer si aggiudica diversi anni di carcere<\/strong><\/h3>\n<p>Il noto e pericoloso hacker rumeno Marcel Laz\u0103r Lehel, conosciuto anche come \u201cGuccifer\u201d, catturato all\u2019inizio di quest\u2019anno in Romania, para abbia ricevuto la lezione che meritava: a met\u00e0 giugno, la corte rumena lo ha condannato a 4 anni di carcere. Durante gli ultimi anni, Marcel aveva hackerato un numero molto alto di account online privati, tra cui la casella di posta della famiglia Bush, dell\u2019ex segretario di stato Colin Power e del capo dei servizi segreti rumeni, George Maior. Come ha affermato il pubblico ministero, tra i metodi dell\u2019hacker, vi era una tecnica per indovinare le risposte alle domande di sicurezza e ottenere cos\u00ec l\u2019accesso agli account desiderati. Ora sta per scontare 7 anni di carcere, considerando che in precedenza aveva gi\u00e0 affrontato una condanna di 3 anni con sospensione della pena.<\/p>\n<p><\/p><blockquote class=\"twitter-pullquote\"><p>I responsabili della campagna ransomware iPhone sono finalmente dietro alle sbarre! #sicurezzaIT #arrestigiugno<\/p><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fkas.pr%2Fhzc8&amp;text=+I+responsabili+della+campagna+ransomware+iPhone+sono+finalmente+dietro+alle+sbarre%21+%23sicurezzaIT+%23arrestigiugno+\" class=\"btn btn-twhite\" data-lang=\"en\" data-count=\"0\" target=\"_blank\" rel=\"noopener nofollow\">Tweet<\/a><\/blockquote><strong><br>\n<\/strong>\n<h3><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/89\/2014\/07\/05232809\/iOSransom.png\" alt=\"\" width=\"180\" height=\"274\">4 anni per aver rubato le credenziali iCloud<\/strong><\/h3>\n<p>Un <a href=\"https:\/\/www.kaspersky.it\/blog\/un-nuovo-malware-ransomware-attacca-gli-utenti-apple\/\" target=\"_blank\" rel=\"noopener\">paio di mesi fa, vi abbiamo parlato di un fatto rilevante<\/a>: un numero sempre maggiore di utenti Apple sta sperimentando un blocco non autorizzato del proprio dispositivo da parte di criminali che chiedono un riscatto monetario a cambio dello sblocco del telefono, tablet o computer. Il problema si \u00e8 verificato in diversi paesi tra cui la Russia, dove la polizia \u00e8 riuscita finalmente ad acchiappare i frodatori. All\u2019inizio di questo mese, due giovani moscoviti di 23 e 16 anni sono stati arrestati per aver hackerato un numero molto alto di account. I criminali avevano usato due metodi: il primo prevedeva hackerare gli account email della vittima ed elaborare pagine di phishing per mettere le mani sulle credenziali Apple ID. Il secondo metodo consisteva nel collegare i dispositivi ad account preimpostati e usare \u201cvarie risorse Internet per creare pubblicit\u00e0\u201d. Gli ads promettevano l\u2019accesso agli account Apple ID che contenevano un \u201cgrande numero di contenuti multimediali\u201d. Nel momento in cui qualcuno accettava l\u2019offerta e collegava i propri dispositivi all\u2019account, gli hacker entravano nei dispositivi. Ora entrambi i ragazzi rischiano fino a 4 anni di carcere.<\/p>\n<h3><strong>10 anni per frode informatica<\/strong><\/h3>\n<p>Pare proprio che lo scorso \u00e8 stato un mese molto buono per la corte russa dato che molte delle notizie riguardano questo paese. Le autorit\u00e0 locali, con l\u2019aiuto di un esperto di Kaspersky Lab, hanno individuato un gruppo di persone che si sospetta abbiano rubato milioni e milioni di dollari dagli account aziendali e privati di una banca. Pare che i criminali stessero usando un malware speciale da loro implementato nei computer delle vittime per hackerare gli account della banca online. Dopo essere penetrati negli account online, sono riusciti a trasferire il denaro delle vittime su account controllati da loro, e a prelevare cos\u00ec, senza grandi problemi e in diverse citt\u00e0, i soldi che desideravano da qualsiasi sportello bancario. La polizia ha affermato che la gang aveva quasi rubato un milione di dollari. Peccato che se verranno condannati colpevoli, l\u2019unico cosa che rimarr\u00e0 loro sono 10 anni di carcere.<\/p>\n<div class=\"pullquote\">L\u2019FBI ha identificato Evgeniy Mikhailovich Bogachev, accusato di essere il responsabile dell\u2019operazione GameOver Zeus.<\/div>\n<h3><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/89\/2014\/07\/05232809\/Evgeniy-Bogachev.jpg\" alt=\"\" width=\"200\" height=\"200\">FBI e autorit\u00e0 europee alla ricerca del responsabile della botnet GameOver Zeus<\/strong><\/h3>\n<p>Venerd\u00ec, le forze dell\u2019ordine europee e statunitensi, tra cui Europol e l\u2019FBI, hanno portato a termine <a href=\"https:\/\/www.kaspersky.it\/blog\/smantellata-la-botnet-gameover-zeus-e-ora-che-succede\/\" target=\"_blank\" rel=\"noopener\">lo smantellamento della botnet GameOver Zeus<\/a>, prendendo il controllo dei server e mandando all\u2019aria l\u2019intera operazione. Le autorit\u00e0 affermano che la stessa botnet \u00e8 stata usata per diffondere il ransomware Cryptolocker. Ora le forze dell\u2019ordine sono alla ricerca di un uomo di 30 anni russo che si pensa collegato in qualche modo all\u2019operazione. Il 30 maggio, le autorit\u00e0 del European Cybercrime Center (EC3) hanno iniziato a collaborare con diverse aziende di sicurezza e ricercatori IT. L\u2019obiettivo? Smantellare la botnet e prendere il controllo dei server, parte integrante della botnet. Shadowserver Foundation, Abuse.ch, CrowdStrike, Microsoft e molte altre aziende hanno preso parte allo smantellamento. L\u2019FBI ha identificato Evgeniy Mikhailovich Bogachev, accusato di essere il responsabile dell\u2019operazione GameOver Zeus. Il Dipartimento di Giustizia ha accusato Bogachev di cospirazione, frode informatica, <em>computer hacking<\/em>, frode bancaria e riciclaggio di denaro in relazione all\u2019operazione GameOver Zeus. Inoltre, le autorit\u00e0 hanno affermato che l\u2019imputato \u00e8 responsabile dell\u2019intera infrastruttura Cryptolocker.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo a giugno ed \u00e8 arrivata finalmente l\u2019estate. Ma i cybercriminali e le forze dell\u2019ordine non vanno in vacanza. Diamo dunque un\u2019occhiata ai principali arresti dello scorso mese. <\/p>\n","protected":false},"author":214,"featured_media":4288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2641,12],"tags":[1127,632,54,111,212],"class_list":{"0":"post-4287","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-threats","8":"category-news","9":"tag-arresti-giugno-2014","10":"tag-cybercriminali","11":"tag-hacker","12":"tag-privacy","13":"tag-sicurezza-it"},"hreflang":[{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/i-principali-casi-di-cybercrimine-del-mese-giugno-2014\/4287\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.it\/blog\/tag\/arresti-giugno-2014\/","name":"arresti giugno 2014"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/4287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/comments?post=4287"}],"version-history":[{"count":4,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/4287\/revisions"}],"predecessor-version":[{"id":24524,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/4287\/revisions\/24524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media\/4288"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media?parent=4287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/categories?post=4287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/tags?post=4287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}