{"id":23085,"date":"2020-11-04T09:02:48","date_gmt":"2020-11-04T07:02:48","guid":{"rendered":"https:\/\/www.kaspersky.it\/blog\/?p=23085"},"modified":"2020-11-03T11:45:18","modified_gmt":"2020-11-03T09:45:18","slug":"nextcloud-scan-engine","status":"publish","type":"post","link":"https:\/\/www.kaspersky.it\/blog\/nextcloud-scan-engine\/23085\/","title":{"rendered":"Strumenti di collaborazione e sicurezza"},"content":{"rendered":"<p>Per molte aziende, il passaggio in massa del personale allo smart working ha evidenziato la necessit\u00e0 di nuovi strumenti. Anni di messa a punto dei meccanismi di interazione dei dipendenti sono andati in fumo in poco tempo, mentre i team IT si sono affannati a distribuire soluzioni di collaborazione pronte all\u2019uso. Queste soluzioni hanno suscitato non meno interesse tra i criminali informatici, che vi hanno visto un\u2019opportunit\u00e0 per ottenere l\u2019accesso remoto ai sistemi informatici delle aziende, con lo scopo di diffondere i propri malware sulle reti aziendali.<\/p>\n<h2>Un nuovo panorama di minacce<\/h2>\n<p>Il problema delle soluzioni di collaborazione \u00e8 che in qualsiasi momento possono essere trasformate in veicoli per diffondere l\u2019infezione in tutta la rete aziendale. Un solo dipendente negligente (che utilizza una password ovvia, accede alla risorsa da un dispositivo compromesso, apre un allegato dannoso, ecc.) pu\u00f2 esporre l\u2019ambiente di lavoro ad un attacco, che si colleghi dalla sua postazione in ufficio o dallo studio di casa.<\/p>\n<p>L\u2019impennata di interesse per piattaforme di questo tipo ha portato a una saturazione del mercato di programmi semplici e pi\u00f9 orientati verso la comodit\u00e0 e meno alla sicurezza. Il problema della sicurezza degli strumenti di collaborazione \u00e8 emerso di tanto in tanto nelle notizie durante la primavera e l\u2019estate 2020. Di conseguenza, quando il momento di confusione si \u00e8 attenuato, le aziende che si erano preventivamente occupate di tecnologie di protezione hanno ottenuto un vantaggio dal punto di vista del marketing.<\/p>\n<h2>Come proteggere la vostra piattaforma di collaborazione<\/h2>\n<p>Per la scelta di un sistema di collaborazione sicuro, generalmente i clienti prendono in considerazione diversi aspetti: la tipologia di cifratura offerta, la disponibilit\u00e0 di autenticazione multifattoriale, la posizione fisica del server di archiviazione e i metodi di protezione dei dati. Per quanto riguarda quest\u2019ultimo aspetto, possiamo fornire assistenza grazie a Kaspersky Scan Engine, una delle nostre soluzioni per clienti aziendali e partner tecnologici che si integra facilmente con qualsiasi prodotto software e che analizza i file che passano attraverso l\u2019ambiente di collaborazione alla ricerca di malware.<\/p>\n<h2>Protezione di Nextcloud<\/h2>\n<p>Nextcloud, che si interessa molto della sicurezza degli utenti, ha attivato Kaspersky Scan Engine come file antivirus nella sua piattaforma di collaborazione. Nextcloud \u00e8 implementata su un cloud privato dal lato client e supporta la connessione di vari tipi di dispositivi utente. In altre parole, nell\u2019ambiente di lavoro condiviso, i file possono essere caricati da sistemi operativi totalmente diversi. In teoria, questa flessibilit\u00e0 aumenta il rischio di propagazione delle minacce: in primo luogo, perch\u00e9 le soluzioni di sicurezza per le diverse piattaforme possono fornire diversi livelli di protezione; in secondo luogo, perch\u00e9 gli utenti di alcuni tipi di sistemi (come Linux) tendono a non utilizzare alcuna soluzione antivirus.<\/p>\n<p>Per evitare che un utente finale comprometta inavvertitamente (o deliberatamente) l\u2019ambiente di collaborazione aziendale scaricando e distribuendo un file dannoso, i creatori della piattaforma hanno sviluppato un\u2019applicazione di sicurezza alla quale pu\u00f2 collegarsi il nostro motore di analisi. Per utilizzarla, i clienti aziendali devono avere a disposizione Kaspersky Scan Engine, installare l\u2019app Nextcloud Antivirus e configurarla per farla funzionare con la nostra soluzione. Fatto questo, l\u2019app esegue la scansione di ogni file caricato sul server alla ricerca di codici dannosi, rilevando ransomware, cryptominer, spyware e altri oggetti pericolosi. Il motore riceve informazioni in tempo reale sulle ultime minacce attraverso Kaspersky Security Network e pu\u00f2 respingere un attacco in pochi minuti dopo la rilevazione della minaccia da parte delle nostre tecnologie.<\/p>\n<p>Per installare Nextcloud Antivirus e connettere il nostro motore, troverete maggiori informazioni sulla nostra pagina dedicata a <a href=\"https:\/\/www.kaspersky.it\/scan-engine?icid=it_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_wpplaceholder_______\" target=\"_blank\" rel=\"noopener\">Kaspersky Scan Engine<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un ambiente di lavoro condiviso pu\u00f2 facilitare la diffusione di malware. Ma noi abbiamo gli strumenti per fermarli. <\/p>\n","protected":false},"author":700,"featured_media":23087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2364,2955,2956],"tags":[3323,2885,3290],"class_list":{"0":"post-23085","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-business","8":"category-enterprise","9":"category-smb","10":"tag-lavoro-da-remoto","11":"tag-partner-tecnologici","12":"tag-smart-working"},"hreflang":[{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/nextcloud-scan-engine\/23085\/"},{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/nextcloud-scan-engine\/20390\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/nextcloud-scan-engine\/24072\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/nextcloud-scan-engine\/29277\/"},{"hreflang":"tr","url":"https:\/\/www.kaspersky.com.tr\/blog\/nextcloud-scan-engine\/8937\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/nextcloud-scan-engine\/37352\/"},{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/nextcloud-scan-engine\/15802\/"},{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/nextcloud-scan-engine\/16260\/"},{"hreflang":"pl","url":"https:\/\/plblog.kaspersky.com\/nextcloud-scan-engine\/14069\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/nextcloud-scan-engine\/25524\/"},{"hreflang":"zh","url":"https:\/\/www.kaspersky.com.cn\/blog\/nextcloud-scan-engine\/12319\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/nextcloud-scan-engine\/29410\/"},{"hreflang":"nl","url":"https:\/\/www.kaspersky.nl\/blog\/nextcloud-scan-engine\/26225\/"},{"hreflang":"ru-kz","url":"https:\/\/blog.kaspersky.kz\/nextcloud-scan-engine\/22984\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.it\/blog\/tag\/smart-working\/","name":"smart working"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/23085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/users\/700"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/comments?post=23085"}],"version-history":[{"count":5,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/23085\/revisions"}],"predecessor-version":[{"id":23223,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/23085\/revisions\/23223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media\/23087"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media?parent=23085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/categories?post=23085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/tags?post=23085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}