{"id":14324,"date":"2017-10-16T11:50:27","date_gmt":"2017-10-16T09:50:27","guid":{"rendered":"https:\/\/www.kaspersky.it\/blog\/?p=14324"},"modified":"2019-11-22T11:09:57","modified_gmt":"2019-11-22T09:09:57","slug":"krackattack","status":"publish","type":"post","link":"https:\/\/www.kaspersky.it\/blog\/krackattack\/14324\/","title":{"rendered":"KRACK: e la connessione Wi-Fi non \u00e8 pi\u00f9 sicura"},"content":{"rendered":"<p>La maggior parte delle vulnerabilit\u00e0 passano inosservata alla popolazione mondiale, anche quando colpiscono milioni di persone. Ma questa notizia fresca fresca \u00e8 probabilmente pi\u00f9 importante della <a href=\"https:\/\/threatpost.com\/2013-yahoo-breach-affected-all-3-billion-accounts\/128259\/\" target=\"_blank\" rel=\"noopener nofollow\">recente fuga di dati di Yahoo <\/a>e riguarda miliardi di persone in tutto il mondo. I ricercatori hanno individuato diverse vulnerabilit\u00e0 che mettono a repentaglio la sicurezza di tutte le reti Wi-Fi.<\/p>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"kis-trial-vpn\">\n<p>Una <a href=\"https:\/\/papers.mathyvanhoef.com\/ccs2017.pdf\" target=\"_blank\" rel=\"noopener nofollow\">ricerca<\/a> pubblicata da pochissimo descrive in che modo si potrebbe hackerare in teoria qualsiasi rete Wi-Fi che si affidi al sistema di cifratura WPA o WPA2. WPA \u00e8 lo standard della connessione Wi-Fi moderna, per questo motivo qualsiasi rete Wi-Fi del mondo \u00e8 a rischio.<\/p>\n<p>Si tratta di una ricerca piuttosto tecnica, non entreremo in dettagli ma di seguito vi riassumeremo ci\u00f2 che \u00e8 stato scoperto.<\/p>\n<h3><strong>Come funziona KRACK<\/strong><\/h3>\n<p>I ricercatori hanno riscontrato che i dispositivi che utilizzano i pi\u00f9 popolari sistemi operativi quali Android, Ios, Linux, macOS, Windows e altri sono vulnerabili ad alcune varianti di questo attacco, parliamo in pratica di qualsiasi dispositivo. L\u2019attacco in questione si chiama <a href=\"https:\/\/www.krackattacks.com\/\" target=\"_blank\" rel=\"noopener nofollow\">KRACK<\/a>, acronimo di <em>key reinstallation attack<\/em>.<\/p>\n<p>I ricercatori descrivono in particolare la dinamica dell\u2019attacco sui dispositivi con Android 6. Il cybercriminale imposta una rete Wi-Fi con lo stesso nome (SSID) della rete obiettivo, appartenente a un utente specifico. Quando il cybercriminale registra che l\u2019utente sta per collegarsi alla rete originale, invia speciali pacchetti di dati che fanno s\u00ec che il dispositivo passi a un altro canale e si colleghi alla rete fasulla ma con lo stesso nome di quella originale.<\/p>\n<p>Dopodici\u00f2, sfruttando una falla nell\u2019implementazione dei protocolli di cifratura, cambia la chiave di cifratura impiegata dall\u2019utente e la sostituisce con una stringa di zeri e ottiene cos\u00ec accesso a tutte le informazioni che l\u2019utente carica o scarica.<\/p>\n<p>Si potrebbe ribattere che c\u2019\u00e8 un altro livello di sicurezza, ovvero la cifratura degli stessi siti Internet, SSL o HTTPS. Tuttavia, grazie a una semplice utility che si chiama SSLstrip si pu\u00f2 impostare un punto di accesso falso che costringerebbe il browser a comunicare con versioni HTTP non cifrate dei siti invece di quelle cifrate (le versioni HTTPS), nel caso in cui il sito non sia stato cifrato nella maniera corretta (il che capita molto spesso, anche su siti piuttosto importanti).<\/p>\n<p>Se si impiega questa utility nelle rete falsa, il cybercriminale pu\u00f2 accedere a username e password dell\u2019utente in testo semplice, insomma pu\u00f2 appropriarsene senza problemi.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" type=\"text\/html\" width=\"640\" height=\"390\" src=\"https:\/\/www.youtube.com\/embed\/Oh4WURZoR98?version=3&amp;rel=1&amp;fs=1&amp;showsearch=0&amp;showinfo=1&amp;iv_load_policy=1&amp;wmode=transparent\" frameborder=\"0\" allowfullscreen=\"true\"><\/iframe><\/span><\/p>\n<h3><strong>Come mettere al sicuro i propri dati?<\/strong><\/h3>\n<p>Sapere che quasi tutti i dispositivi connessi a qualsiasi rete Wi-Fi siano vulnerabili a KRACK fa preoccupare (molto di qualsiasi altri attacco), ma non \u00e8 la fine del mondo. Ecco un paio di consigli per proteggervi da attacchi KRACK nel caso qualche malintenzionato decida di perpetrarli sui vostri dispositivi.<\/p>\n<ul>\n<li>Verificate sempre che ci sia il famoso lucchetto verde nella barra degli indirizzi del browser. Il lucchetto indica la presenza di una connessione HTTPS (cifrata e quindi sicura) per il sito che state visitando. Se qualcuno cerca di utilizzare SSLstrip, il browser sar\u00e0 obbligato a utilizzare la versione HTTP del sito e il lucchetto verde scomparir\u00e0. Se il lucchetto \u00e8 ancora l\u00ec, la connessione \u00e8 sicura;<\/li>\n<li>I ricercatori hanno avvisato alcune case produttrici di apparati di rete (compresa la <a href=\"https:\/\/www.wi-fi.org\/\" target=\"_blank\" rel=\"noopener nofollow\">Wi-Fi Alliance<\/a>, che si occupa di standardizzare i protocolli) prima di pubblicare il loro lavoro. La maggior parte di loro sta per pubblicare aggiornamenti del firmware per risolvere questa vulnerabilit\u00e0. Verificate quindi se ci sono nuovi aggiornamenti del firmware e installateli il prima possibile;<\/li>\n<li>Potete proteggere la connessione mediante una VPN, che conferisce un livello di cifratura aggiuntivo ai dati che passano per il vostro dispositivo. Qui potete avere maggiori informazioni su cosa sia <a href=\"https:\/\/www.kaspersky.it\/blog\/vpn-what-you-need-to-know\/10005\/\" target=\"_blank\" rel=\"noopener\">una VPN\u00a0 e come scegliere quella pi\u00f9 adatta a voi<\/a>, oppure potete direttamente optare per <a href=\"https:\/\/www.kaspersky.it\/secure-connection?redef=1&amp;reseller=it_kdpost_acq_ona_smm__onl_b2c__sitelink_______\" target=\"_blank\" rel=\"noopener\">Kaspersky Secure Connection<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Qualsiasi rete Wi-Fi che usa i sistemi di cifratura WAP o WAP2 \u00e8 vulnerabile a questo attacco. Vediamo come funziona e come difendersi.<\/p>\n","protected":false},"author":675,"featured_media":14325,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2641],"tags":[2239,119,2601,2521,2602,2598,638,45,49,2599,2600],"class_list":{"0":"post-14324","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-threats","8":"tag-consigli","9":"tag-attacco","10":"tag-chiave","11":"tag-cifratura","12":"tag-krack","13":"tag-krackattack","14":"tag-minacce","15":"tag-sicurezza","16":"tag-wi-fi","17":"tag-wpa","18":"tag-wpa2"},"hreflang":[{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/krackattack\/14324\/"},{"hreflang":"en-in","url":"https:\/\/www.kaspersky.co.in\/blog\/krackattack\/11579\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/krackattack\/9751\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/krackattack\/13011\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/krackattack\/11932\/"},{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/krackattack\/11578\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/krackattack\/14579\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/krackattack\/19022\/"},{"hreflang":"tr","url":"https:\/\/www.kaspersky.com.tr\/blog\/krackattack\/4272\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/krackattack\/19798\/"},{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/krackattack\/9635\/"},{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/krackattack\/9742\/"},{"hreflang":"pl","url":"https:\/\/plblog.kaspersky.com\/krackattack\/8343\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/krackattack\/14970\/"},{"hreflang":"zh","url":"https:\/\/www.kaspersky.com.cn\/blog\/krackattack\/8667\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/krackattack\/18448\/"},{"hreflang":"en-au","url":"https:\/\/www.kaspersky.com.au\/blog\/krackattack\/18915\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/krackattack\/18905\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.it\/blog\/tag\/wi-fi\/","name":"wi-fi"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/14324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/users\/675"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/comments?post=14324"}],"version-history":[{"count":3,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/14324\/revisions"}],"predecessor-version":[{"id":18724,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/14324\/revisions\/18724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media\/14325"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media?parent=14324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/categories?post=14324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/tags?post=14324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}