{"id":14129,"date":"2017-08-21T16:32:19","date_gmt":"2017-08-21T14:32:19","guid":{"rendered":"https:\/\/www.kaspersky.it\/blog\/?p=14129"},"modified":"2020-05-19T20:20:23","modified_gmt":"2020-05-19T18:20:23","slug":"not-a-virus","status":"publish","type":"post","link":"https:\/\/www.kaspersky.it\/blog\/not-a-virus\/14129\/","title":{"rendered":"Se non \u00e8 un virus, allora cos&#8217;\u00e8?"},"content":{"rendered":"<p>A volte, <a href=\"https:\/\/kas.pr\/e2v1\" target=\"_blank\" rel=\"noopener\">Kaspersky Internet Security<\/a> apre una finestra con un riquadro giallo e informa l\u2019utente che \u00e8 stato rilevato nel computer un \u201cnon virus\u201d . Naturalmente, qualsiasi utente curioso potrebbe chiedersi: se non \u00e8 un virus, perch\u00e9 l\u2019applicazione antivirus invia questo avviso?<\/p>\n<p>In realt\u00e0, il vostro antivirus ha motivo di preoccuparsi. Anche se l\u2019oggetto in questione non \u00e8 in realt\u00e0 un programma dannoso, \u00e8 qualcosa di cui, in qualche modo, dovreste essere a conoscenza. Approfondiamo la definizione di \u201cnon virus\u201d, che tipo di applicazioni attivano l\u2019avviso e che cosa dovreste fare al riguardo.<\/p>\n<p>In linea generale, Kaspersky Internet Security associa il termine \u201cnon virus\u201d a due tipi di applicazioni: adware e riskware. Entrambi i tipi non sono dannosi per natura, quindi non possono essere chiamati virus. Tuttavia, gli utenti dovrebbero sapere che sono installati; le applicazioni potrebbero fare qualcosa di indesiderato.<\/p>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"ksc-trial\">\n<h2>Che cos\u2019\u00e8 un adware?<\/h2>\n<p>Un adware \u00e8 un software con materiale pubblicitario. Questo tipo di software pu\u00f2 mostrarvi annunci pubblicitari, modificare i risultati della ricerca, raccogliere i dati dell\u2019utente per mostrare pubblicit\u00e0 contestuale mirata, o tutto quanto riportato sopra.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14131 aligncenter\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/89\/2017\/08\/23163549\/852-1-en13-83043.png\" alt=\"\" width=\"355\" height=\"429\"><\/p>\n<p>Un adware tecnicamente non \u00e8 dannoso, ma non \u00e8 nemmeno nulla di buono. Si scatena una gran confusione quando <a href=\"https:\/\/www.kaspersky.it\/blog\/eliminare-gli-adware\/5519\/\" target=\"_blank\" rel=\"noopener\">alcune dozzine di applicazioni adware si infilano in un computer e cominciano a competere l\u2019una con l\u2019altra per le risorse.<\/a><\/p>\n<p>Detto questo, un adware \u00e8 un software legittimo installato sul computer con il consenso formale degli utenti, \u00a0il trucco \u00e8 che gli utenti potrebbero non notare una casella di controllo preselezionata durante l\u2019installazione di un\u2019altra applicazione e quindi accettano di installare l\u2019adware. Altri casi di tali trucchetti abbondano, ma sono tutti uguali in una cosa: se gli utenti leggono tutto con attenzione, allora possono rifiutare l\u2019installazione dell\u2019adware.<\/p>\n<p>Se l\u2019adware non notifica all\u2019utente il suo tentativo di installarsi sul computer, allora Kaspersky Internet Security lo considera come un Trojan dannoso. In tal caso, la notifica avr\u00e0 un riquadro rosso, non giallo, e l\u2019applicazione verr\u00e0 bloccata immediatamente. A tal proposito, potete consultare <a href=\"https:\/\/www.kaspersky.it\/blog\/antivirus-notifications\/13102\/\" target=\"_blank\" rel=\"noopener\">quest\u2019articolo in cui spieghiamo <\/a>a cosa si riferiscono i colori dei riquadri delle finestre di notifica nei nostri prodotti.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"NT5azs7uPF\"><p><a href=\"https:\/\/www.kaspersky.it\/blog\/eliminare-gli-adware\/5519\/\" target=\"_blank\" rel=\"noopener\">Eliminare gli adware: che fatica!<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u201cEliminare gli adware: che fatica!\u201d \u2014 Daily - Italian - Italy - www.kaspersky.it\/blog\" src=\"https:\/\/www.kaspersky.it\/blog\/eliminare-gli-adware\/5519\/embed\/#?secret=6lusR1VUc5#?secret=NT5azs7uPF\" data-secret=\"NT5azs7uPF\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<h2>Che cos\u2019\u00e8 un riskware?\u00a0<\/h2>\n<p>Il <a href=\"https:\/\/securelist.com\/threats\/riskware\/\" target=\"_blank\" rel=\"noopener\">riskware<\/a> \u00e8 un caso leggermente diverso. Le applicazioni di questo tipo sono state inizialmente create come strumenti utili e potrebbero essere utilizzati su un computer per i loro scopi prefissati. Ma spesso i malfattori installano il riskware (certamente senza che l\u2019utente ne sia a conoscenza) per perseguire i propri obiettivi. Potete consultare l\u2019elenco completo dei tipi di applicazione che consideriamo riskware <a href=\"https:\/\/securelist.com\/threats\/riskware\/\" target=\"_blank\" rel=\"noopener\">qui<\/a>.<\/p>\n<p>Ad esempio, il software di gestione del computer in remoto (amministratore remoto) \u00e8 considerato un riskware. Se avete installato voi stessi una di queste applicazioni e sapete cosa state facendo, allora non c\u2019\u00e8 niente di male ad averlo. Tuttavia, questo tipo di applicazione \u00e8 spesso incluso come parte di un pacchetto malware; in questo caso, gli utenti devono sapere di cosa si tratta.<\/p>\n<p>Un altro esempio sono i download manager. Molti di questi rendono facile e conveniente scaricare file, ma alcuni di essi sembrano operare al limite delle regole, ad esempio tentando di scaricare file aggiuntivi durante la visualizzazione di una notifica utilizzando un carattere grigio su sfondo grigio.<\/p>\n<p>Un altro tipo popolare di riskware sono le barre degli strumenti del browser, che potrebbero anche essere adware, a seconda delle funzioni supportate e della persistenza. E alcune estensioni del browser possono essere considerate riskware.<\/p>\n<p>Inoltre, i miner rientrano nella categoria dei riskware. I miner sono applicazioni per il <a href=\"https:\/\/www.kaspersky.it\/blog\/mining-easy-explanation\/13996\/\" target=\"_blank\" rel=\"noopener\">mining di bitcoin<\/a>. Inutile dire che, qualora foste voi ad aver scelto di installare un miner sul vostro computer, allora dovrebbe essere tutto a posto. Ma se qualcun altro l\u2019ha fatto senza il vostro consenso, allora i software installati stanno consumando le risorse del vostro computer a loro vantaggio.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"FXMuG8lBUJ\"><p><a href=\"https:\/\/www.kaspersky.it\/blog\/mining-easy-explanation\/13996\/\" target=\"_blank\" rel=\"noopener\">In breve: mining di Bitcoin<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u201cIn breve: mining di Bitcoin\u201d \u2014 Daily - Italian - Italy - www.kaspersky.it\/blog\" src=\"https:\/\/www.kaspersky.it\/blog\/mining-easy-explanation\/13996\/embed\/#?secret=2fdropvkRh#?secret=FXMuG8lBUJ\" data-secret=\"FXMuG8lBUJ\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Per impostazione predefinita, Kaspersky Internet Security <em>non mostra le<\/em> <em>notifiche<\/em>\u00a0 del rilevamento di riskware. Ora, se entrate nella sezione \u201cMinacce ed Esclusioni\u201d delle impostazioni e controllate l\u2019opzione per il rilevamenti di altri software, Kaspersky Internet Security vi informer\u00e0 anche sui riskware.<\/p>\n<p>Tuttavia, vi informer\u00e0 solamente. L\u2019antivirus non blocca o elimina il riskware per impostazione predefinita, in modo da non ostacolare l\u2019uso legittimo di queste applicazioni. Infatti, non vedrete la parola \u201criskware\u201d in nessuna delle notifiche. Saranno mostrate solo informazioni specifiche, che vi indicheranno se un\u2019applicazione \u00e8 per amministratore remoto, se \u00e8 un downloader o qualcos\u2019altro.<\/p>\n<p>Non appena il riskware inizia a scaricare qualsiasi componente malware, questo verr\u00e0 riclassificato come Trojan e bloccato, indipendentemente dal fatto che sia stata selezionata l\u2019opzione di rilevamento di altri software.<\/p>\n<h2>\u00c8 stato rilevato un adware o un riskware. Qual \u00e8 il passo successivo?<\/h2>\n<p><a href=\"https:\/\/www.kaspersky.it\/security-cloud?icid=it_kdailyplacehold_pla_ona_afm__onl_b2c_kasperskydaily_lnk_______#buy-section\" target=\"_blank\" rel=\"noopener\">Kaspersky Security Cloud<\/a> mostra le notifiche di rilevamento per tali applicazioni in modo che voi sappiate che sono installate nel vostro computer. \u00c8 possibile che voi le abbiate installiate intenzionalmente: come abbiamo detto, i riskware possono anche essere molto utili. In questo caso, non c\u2019\u00e8 motivo di preoccuparsi.<\/p>\n<p>\u00c8 anche possibile che un altro \u201cnon-virus\u201d si sia intrufolato nel vostro computer senza che voi lo abbiate notato. In questo caso, \u00e8 necessario sapere se l\u2019applicazione \u00e8 correlata a un riskware o a un adware. Ecco perch\u00e9 gli utenti hanno la possibilit\u00e0 di scegliere cosa fare con l\u2019applicazione. Se non l\u2019avete installata voi, probabilmente dovreste eliminarla.<\/p>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"ksc-trial\">\n","protected":false},"excerpt":{"rendered":"<p>Che cosa dovreste fare se il vostro antivirus rileva qualcosa che chiama &#8220;not-a-virus&#8221; (un non-virus)? Che tipo di applicazioni si trovano dietro questo messaggio e di che cosa si sta parlando?<\/p>\n","protected":false},"author":675,"featured_media":14130,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2641,14],"tags":[800,2369,22,638,2533,2530,2532,2531,83],"class_list":{"0":"post-14129","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-threats","8":"category-products","9":"tag-adware","10":"tag-annunci","11":"tag-malware-2","12":"tag-minacce","13":"tag-nonvirus","14":"tag-not-a-virus","15":"tag-pornware","16":"tag-riskware","17":"tag-virus"},"hreflang":[{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/not-a-virus\/14129\/"},{"hreflang":"en-in","url":"https:\/\/www.kaspersky.co.in\/blog\/not-a-virus\/11143\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/not-a-virus\/9211\/"},{"hreflang":"ar","url":"https:\/\/me.kaspersky.com\/blog\/not-a-virus\/4951\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/not-a-virus\/12467\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/not-a-virus\/11660\/"},{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/not-a-virus\/11178\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/not-a-virus\/14121\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/not-a-virus\/18512\/"},{"hreflang":"tr","url":"https:\/\/www.kaspersky.com.tr\/blog\/not-a-virus\/3724\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/not-a-virus\/18015\/"},{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/not-a-virus\/9398\/"},{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/not-a-virus\/10009\/"},{"hreflang":"pl","url":"https:\/\/plblog.kaspersky.com\/not-a-virus\/7291\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/not-a-virus\/14499\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/not-a-virus\/17680\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/not-a-virus\/17729\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.it\/blog\/tag\/adware\/","name":"adware"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/14129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/users\/675"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/comments?post=14129"}],"version-history":[{"count":9,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/14129\/revisions"}],"predecessor-version":[{"id":21728,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/posts\/14129\/revisions\/21728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media\/14130"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/media?parent=14129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/categories?post=14129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.it\/blog\/wp-json\/wp\/v2\/tags?post=14129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}